{"id":330,"count":1,"description":"D\u00e9couvrez notre s\u00e9lection exclusive des meilleurs restaurants du d\u00e9partement Morbihan.","link":"https:\/\/restaurants-de-france.fr\/meilleurs\/category\/bretagne\/morbihan\/","name":"Morbihan","slug":"morbihan","taxonomy":"category","parent":224,"meta":[],"_links":{"self":[{"href":"https:\/\/restaurants-de-france.fr\/meilleurs\/wp-json\/wp\/v2\/categories\/330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/restaurants-de-france.fr\/meilleurs\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/restaurants-de-france.fr\/meilleurs\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/restaurants-de-france.fr\/meilleurs\/wp-json\/wp\/v2\/categories\/224"}],"wp:post_type":[{"href":"https:\/\/restaurants-de-france.fr\/meilleurs\/wp-json\/wp\/v2\/posts?categories=330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}